{"id":14226,"date":"2023-11-07T12:39:49","date_gmt":"2023-11-07T11:39:49","guid":{"rendered":"http:\/\/fondazioneartecrt.it\/opera\/presenza-stanza-ettore-spalletti-2\/"},"modified":"2023-11-07T12:39:49","modified_gmt":"2023-11-07T11:39:49","slug":"presenza-stanza-ettore-spalletti","status":"publish","type":"opera","link":"https:\/\/fondazioneartecrt.it\/en\/artwork\/presenza-stanza-ettore-spalletti\/","title":{"rendered":"Presenza Stanza"},"content":{"rendered":"<div>powdere<\/div>\n<div>d pigment on wood,<\/div>\n","protected":false},"featured_media":0,"template":"","class_list":["post-14226","opera","type-opera","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presenza Stanza - Fondazione Arte CRT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fondazioneartecrt.it\/opera\/presenza-stanza-ettore-spalletti\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presenza Stanza - Fondazione Arte CRT\" \/>\n<meta property=\"og:description\" content=\"powdere d pigment on wood,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fondazioneartecrt.it\/opera\/presenza-stanza-ettore-spalletti\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Arte CRT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/it-it.facebook.com\/fondartecrt\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/api.fondazioneartecrt.it\/rails\/active_storage\/blobs\/eyJfcmFpbHMiOnsibWVzc2FnZSI6IkJBaEpJaWt4TURnMU5URmxPUzFsWlRNNUxUUXpNVEV0T1RFMlpTMHhaakV6TldKallXTXhaalVHT2daRlZBPT0iLCJleHAiOm51bGwsInB1ciI6ImJsb2JfaWQifX0=--9b76ff62ae593998ded9652a0d2e3269df45e4ca\/spalletti-Presenza.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fondazioneartecrt.it\\\/opera\\\/presenza-stanza-ettore-spalletti\\\/\",\"url\":\"https:\\\/\\\/fondazioneartecrt.it\\\/opera\\\/presenza-stanza-ettore-spalletti\\\/\",\"name\":\"Presenza Stanza - Fondazione Arte CRT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fondazioneartecrt.it\\\/en\\\/#website\"},\"datePublished\":\"2023-11-07T11:39:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fondazioneartecrt.it\\\/opera\\\/presenza-stanza-ettore-spalletti\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fondazioneartecrt.it\\\/opera\\\/presenza-stanza-ettore-spalletti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fondazioneartecrt.it\\\/opera\\\/presenza-stanza-ettore-spalletti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fondazioneartecrt.it\\\/en\\\/home-fondazione-arte-crt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presenza Stanza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fondazioneartecrt.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fondazioneartecrt.it\\\/en\\\/\",\"name\":\"Fondazione Arte CRT\",\"description\":\"Fondazione Arte CRT\",\"publisher\":{\"@id\":\"https:\\\/\\\/fondazioneartecrt.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fondazioneartecrt.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fondazioneartecrt.it\\\/en\\\/#organization\",\"name\":\"Fondazione Arte CRT\",\"url\":\"https:\\\/\\\/fondazioneartecrt.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fondazioneartecrt.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fondazioneartecrt.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Screenshot-2026-02-17-alle-09.05.22.png\",\"contentUrl\":\"https:\\\/\\\/fondazioneartecrt.it\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Screenshot-2026-02-17-alle-09.05.22.png\",\"width\":96,\"height\":124,\"caption\":\"Fondazione Arte CRT\"},\"image\":{\"@id\":\"https:\\\/\\\/fondazioneartecrt.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/it-it.facebook.com\\\/fondartecrt\\\/\",\"https:\\\/\\\/www.instagram.com\\\/fondartecrt\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fondazione-per-l-arte-moderna-e-contemporanea-crt\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fondazioneartecrt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presenza Stanza - Fondazione Arte CRT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fondazioneartecrt.it\/opera\/presenza-stanza-ettore-spalletti\/","og_locale":"en_US","og_type":"article","og_title":"Presenza Stanza - Fondazione Arte CRT","og_description":"powdere d pigment on wood,","og_url":"https:\/\/fondazioneartecrt.it\/opera\/presenza-stanza-ettore-spalletti\/","og_site_name":"Fondazione Arte CRT","article_publisher":"https:\/\/it-it.facebook.com\/fondartecrt\/","og_image":[{"url":"https:\/\/api.fondazioneartecrt.it\/rails\/active_storage\/blobs\/eyJfcmFpbHMiOnsibWVzc2FnZSI6IkJBaEpJaWt4TURnMU5URmxPUzFsWlRNNUxUUXpNVEV0T1RFMlpTMHhaakV6TldKallXTXhaalVHT2daRlZBPT0iLCJleHAiOm51bGwsInB1ciI6ImJsb2JfaWQifX0=--9b76ff62ae593998ded9652a0d2e3269df45e4ca\/spalletti-Presenza.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fondazioneartecrt.it\/opera\/presenza-stanza-ettore-spalletti\/","url":"https:\/\/fondazioneartecrt.it\/opera\/presenza-stanza-ettore-spalletti\/","name":"Presenza Stanza - Fondazione Arte CRT","isPartOf":{"@id":"https:\/\/fondazioneartecrt.it\/en\/#website"},"datePublished":"2023-11-07T11:39:49+00:00","breadcrumb":{"@id":"https:\/\/fondazioneartecrt.it\/opera\/presenza-stanza-ettore-spalletti\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fondazioneartecrt.it\/opera\/presenza-stanza-ettore-spalletti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fondazioneartecrt.it\/opera\/presenza-stanza-ettore-spalletti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fondazioneartecrt.it\/en\/home-fondazione-arte-crt\/"},{"@type":"ListItem","position":2,"name":"Presenza Stanza"}]},{"@type":"WebSite","@id":"https:\/\/fondazioneartecrt.it\/en\/#website","url":"https:\/\/fondazioneartecrt.it\/en\/","name":"Fondazione Arte CRT","description":"Fondazione Arte CRT","publisher":{"@id":"https:\/\/fondazioneartecrt.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fondazioneartecrt.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fondazioneartecrt.it\/en\/#organization","name":"Fondazione Arte CRT","url":"https:\/\/fondazioneartecrt.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fondazioneartecrt.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/fondazioneartecrt.it\/wp-content\/uploads\/2026\/02\/Screenshot-2026-02-17-alle-09.05.22.png","contentUrl":"https:\/\/fondazioneartecrt.it\/wp-content\/uploads\/2026\/02\/Screenshot-2026-02-17-alle-09.05.22.png","width":96,"height":124,"caption":"Fondazione Arte CRT"},"image":{"@id":"https:\/\/fondazioneartecrt.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/it-it.facebook.com\/fondartecrt\/","https:\/\/www.instagram.com\/fondartecrt\/","https:\/\/www.linkedin.com\/company\/fondazione-per-l-arte-moderna-e-contemporanea-crt","https:\/\/www.youtube.com\/user\/fondazioneartecrt"]}]}},"_links":{"self":[{"href":"https:\/\/fondazioneartecrt.it\/en\/wp-json\/wp\/v2\/opera\/14226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fondazioneartecrt.it\/en\/wp-json\/wp\/v2\/opera"}],"about":[{"href":"https:\/\/fondazioneartecrt.it\/en\/wp-json\/wp\/v2\/types\/opera"}],"wp:attachment":[{"href":"https:\/\/fondazioneartecrt.it\/en\/wp-json\/wp\/v2\/media?parent=14226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}