{"id":13595,"date":"2023-11-07T12:34:35","date_gmt":"2023-11-07T11:34:35","guid":{"rendered":"http:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri-2\/"},"modified":"2026-03-10T16:06:32","modified_gmt":"2026-03-10T15:06:32","slug":"via-emilia-luigi-ghirri","status":"publish","type":"opera","link":"https:\/\/fondazioneartecrt.it\/en\/artwork\/via-emilia-luigi-ghirri\/","title":{"rendered":"Via Emilia"},"content":{"rendered":"<p>reprint from original negative<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-13595","opera","type-opera","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Via Emilia - Fondazione Arte CRT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Via Emilia - Fondazione Arte CRT\" \/>\n<meta property=\"og:description\" content=\"reprint from original negative\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Arte CRT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/it-it.facebook.com\/fondartecrt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T15:06:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/api.fondazioneartecrt.it\/rails\/active_storage\/blobs\/eyJfcmFpbHMiOnsibWVzc2FnZSI6IkJBaEpJaWsyWmpGalkyTTJNeTB6TmpFMExUUmtPRGN0T0RjMU55MDNNbUpoWkRVM1lqY3paVE1HT2daRlZBPT0iLCJleHAiOm51bGwsInB1ciI6ImJsb2JfaWQifX0=--3c85411b417b61ef26961b98577fb2104e22ef5a\/Ghirri_277.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri\/\",\"url\":\"https:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri\/\",\"name\":\"Via Emilia - Fondazione Arte CRT\",\"isPartOf\":{\"@id\":\"https:\/\/fondazioneartecrt.it\/en\/#website\"},\"datePublished\":\"2023-11-07T11:34:35+00:00\",\"dateModified\":\"2026-03-10T15:06:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/fondazioneartecrt.it\/en\/home-fondazione-arte-crt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Via Emilia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fondazioneartecrt.it\/en\/#website\",\"url\":\"https:\/\/fondazioneartecrt.it\/en\/\",\"name\":\"Fondazione Arte CRT\",\"description\":\"Fondazione Arte CRT\",\"publisher\":{\"@id\":\"https:\/\/fondazioneartecrt.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fondazioneartecrt.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fondazioneartecrt.it\/en\/#organization\",\"name\":\"Fondazione Arte CRT\",\"url\":\"https:\/\/fondazioneartecrt.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/fondazioneartecrt.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fondazioneartecrt.it\/wp-content\/uploads\/2026\/02\/Screenshot-2026-02-17-alle-09.05.22.png\",\"contentUrl\":\"https:\/\/fondazioneartecrt.it\/wp-content\/uploads\/2026\/02\/Screenshot-2026-02-17-alle-09.05.22.png\",\"width\":96,\"height\":124,\"caption\":\"Fondazione Arte CRT\"},\"image\":{\"@id\":\"https:\/\/fondazioneartecrt.it\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/it-it.facebook.com\/fondartecrt\/\",\"https:\/\/www.instagram.com\/fondartecrt\/\",\"https:\/\/www.linkedin.com\/company\/fondazione-per-l-arte-moderna-e-contemporanea-crt\",\"https:\/\/www.youtube.com\/user\/fondazioneartecrt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Via Emilia - Fondazione Arte CRT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri\/","og_locale":"en_US","og_type":"article","og_title":"Via Emilia - Fondazione Arte CRT","og_description":"reprint from original negative","og_url":"https:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri\/","og_site_name":"Fondazione Arte CRT","article_publisher":"https:\/\/it-it.facebook.com\/fondartecrt\/","article_modified_time":"2026-03-10T15:06:32+00:00","og_image":[{"url":"https:\/\/api.fondazioneartecrt.it\/rails\/active_storage\/blobs\/eyJfcmFpbHMiOnsibWVzc2FnZSI6IkJBaEpJaWsyWmpGalkyTTJNeTB6TmpFMExUUmtPRGN0T0RjMU55MDNNbUpoWkRVM1lqY3paVE1HT2daRlZBPT0iLCJleHAiOm51bGwsInB1ciI6ImJsb2JfaWQifX0=--3c85411b417b61ef26961b98577fb2104e22ef5a\/Ghirri_277.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri\/","url":"https:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri\/","name":"Via Emilia - Fondazione Arte CRT","isPartOf":{"@id":"https:\/\/fondazioneartecrt.it\/en\/#website"},"datePublished":"2023-11-07T11:34:35+00:00","dateModified":"2026-03-10T15:06:32+00:00","breadcrumb":{"@id":"https:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fondazioneartecrt.it\/opera\/via-emilia-luigi-ghirri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fondazioneartecrt.it\/en\/home-fondazione-arte-crt\/"},{"@type":"ListItem","position":2,"name":"Via Emilia"}]},{"@type":"WebSite","@id":"https:\/\/fondazioneartecrt.it\/en\/#website","url":"https:\/\/fondazioneartecrt.it\/en\/","name":"Fondazione Arte CRT","description":"Fondazione Arte CRT","publisher":{"@id":"https:\/\/fondazioneartecrt.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fondazioneartecrt.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fondazioneartecrt.it\/en\/#organization","name":"Fondazione Arte CRT","url":"https:\/\/fondazioneartecrt.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fondazioneartecrt.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/fondazioneartecrt.it\/wp-content\/uploads\/2026\/02\/Screenshot-2026-02-17-alle-09.05.22.png","contentUrl":"https:\/\/fondazioneartecrt.it\/wp-content\/uploads\/2026\/02\/Screenshot-2026-02-17-alle-09.05.22.png","width":96,"height":124,"caption":"Fondazione Arte CRT"},"image":{"@id":"https:\/\/fondazioneartecrt.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/it-it.facebook.com\/fondartecrt\/","https:\/\/www.instagram.com\/fondartecrt\/","https:\/\/www.linkedin.com\/company\/fondazione-per-l-arte-moderna-e-contemporanea-crt","https:\/\/www.youtube.com\/user\/fondazioneartecrt"]}]}},"_links":{"self":[{"href":"https:\/\/fondazioneartecrt.it\/en\/wp-json\/wp\/v2\/opera\/13595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fondazioneartecrt.it\/en\/wp-json\/wp\/v2\/opera"}],"about":[{"href":"https:\/\/fondazioneartecrt.it\/en\/wp-json\/wp\/v2\/types\/opera"}],"wp:attachment":[{"href":"https:\/\/fondazioneartecrt.it\/en\/wp-json\/wp\/v2\/media?parent=13595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}